{"id":9439,"count":1,"description":"","link":"https:\/\/delimiter.online\/blog\/tag\/video-game-market-trends\/","name":"video game market trends","slug":"video-game-market-trends","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/delimiter.online\/blog\/wp-json\/wp\/v2\/tags\/9439","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/delimiter.online\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/delimiter.online\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/delimiter.online\/blog\/wp-json\/wp\/v2\/posts?tags=9439"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}