{"id":8462,"count":1,"description":"","link":"https:\/\/delimiter.online\/blog\/tag\/pair-team\/","name":"Pair Team","slug":"pair-team","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/delimiter.online\/blog\/wp-json\/wp\/v2\/tags\/8462","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/delimiter.online\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/delimiter.online\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/delimiter.online\/blog\/wp-json\/wp\/v2\/posts?tags=8462"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}