{"id":5707,"count":3,"description":"","link":"https:\/\/delimiter.online\/blog\/tag\/supergirl\/","name":"Supergirl","slug":"supergirl","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/delimiter.online\/blog\/wp-json\/wp\/v2\/tags\/5707","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/delimiter.online\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/delimiter.online\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/delimiter.online\/blog\/wp-json\/wp\/v2\/posts?tags=5707"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}